{"id":854,"date":"2026-05-04T17:15:00","date_gmt":"2026-05-04T20:15:00","guid":{"rendered":"https:\/\/ibateagora.com.br\/?p=854"},"modified":"2026-05-06T10:05:51","modified_gmt":"2026-05-06T13:05:51","slug":"sao-carlos-avanca-para-se-consolidar-como-polo-nacional-de-reliquias-sagradas","status":"publish","type":"post","link":"https:\/\/ibateagora.com.br\/index.php\/2026\/05\/04\/sao-carlos-avanca-para-se-consolidar-como-polo-nacional-de-reliquias-sagradas\/","title":{"rendered":"S\u00e3o Carlos avan\u00e7a para se consolidar como polo nacional de rel\u00edquias sagradas"},"content":{"rendered":"<p>A Catedral de S\u00e3o Carlos Borromeu, em S\u00e3o Carlos, no interior paulista, iniciou uma nova etapa em seu projeto de valoriza\u00e7\u00e3o das rel\u00edquias sagradas e busca se firmar como refer\u00eancia nacional nesse campo da devo\u00e7\u00e3o cat\u00f3lica. A iniciativa ganhou for\u00e7a ap\u00f3s a incorpora\u00e7\u00e3o de rel\u00edquias da Santa Cruz ao acervo permanente da igreja e com a oficializa\u00e7\u00e3o de um especialista para conduzir o culto diocesano desses objetos de f\u00e9.<\/p>\n<p>A decis\u00e3o foi chancelada pelo bispo diocesano Dom Luiz Carlos Dias, que designou F\u00e1bio Tucci Farah para a fun\u00e7\u00e3o de respons\u00e1vel oficial pelo culto de rel\u00edquias sagradas na Diocese de S\u00e3o Carlos. Farah j\u00e1 atua na mesma \u00e1rea na Arquidiocese de S\u00e3o Paulo desde 2016 e \u00e9 reconhecido por estudos ligados \u00e0 arqueologia sacra e \u00e0 autentica\u00e7\u00e3o de rel\u00edquias.<\/p>\n<p>A proposta da diocese \u00e9 ampliar o papel da catedral como espa\u00e7o de ora\u00e7\u00e3o, peregrina\u00e7\u00e3o e difus\u00e3o do conhecimento sobre esse patrim\u00f4nio religioso. O projeto prev\u00ea, inclusive, a cria\u00e7\u00e3o de uma capela dedicada aos doze ap\u00f3stolos, reunindo rel\u00edquias de cada um deles, al\u00e9m de um local reservado a S\u00e3o Paulo, uma das figuras centrais do cristianismo.<\/p>\n<p>O movimento refor\u00e7a a liga\u00e7\u00e3o hist\u00f3rica entre o templo e seu padroeiro, S\u00e3o Carlos Borromeu, conhecido por sua forte devo\u00e7\u00e3o \u00e0s rel\u00edquias. Segundo a tradi\u00e7\u00e3o cat\u00f3lica lembrada no texto-base, o santo recorreu a um dos cravos da Paix\u00e3o de Cristo durante um per\u00edodo de peste em Mil\u00e3o, conduzindo prociss\u00f5es em ora\u00e7\u00e3o pelo fim da trag\u00e9dia.<\/p>\n<p>Al\u00e9m do aspecto devocional, a diocese tamb\u00e9m quer transformar S\u00e3o Carlos em um centro de estudo e divulga\u00e7\u00e3o sobre rel\u00edquias sagradas. A expectativa \u00e9 que, nos pr\u00f3ximos anos, o munic\u00edpio passe a atrair n\u00e3o apenas fi\u00e9is, mas tamb\u00e9m pesquisadores e interessados na hist\u00f3ria da Igreja. A ideia \u00e9 somar essa nova voca\u00e7\u00e3o religiosa \u00e0 imagem j\u00e1 conhecida da cidade como refer\u00eancia em tecnologia.<\/p>\n<p>O texto que embasa a iniciativa destaca ainda que a venera\u00e7\u00e3o \u00e0s rel\u00edquias tem origem nos primeiros s\u00e9culos do cristianismo e segue presente na vida da Igreja, especialmente em santu\u00e1rios que recebem peregrinos em busca de ora\u00e7\u00e3o, convers\u00e3o e fortalecimento da f\u00e9. Nesse contexto, a Catedral de S\u00e3o Carlos Borromeu pretende ampliar sua relev\u00e2ncia no cen\u00e1rio cat\u00f3lico brasileiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Catedral de S\u00e3o Carlos Borromeu, em S\u00e3o Carlos, no interior paulista, iniciou uma nova etapa em seu projeto de valoriza\u00e7\u00e3o das rel\u00edquias sagradas e busca se firmar como refer\u00eancia nacional nesse campo da devo\u00e7\u00e3o cat\u00f3lica. A iniciativa ganhou for\u00e7a ap\u00f3s a incorpora\u00e7\u00e3o de rel\u00edquias da Santa Cruz ao acervo permanente da igreja e com<\/p>\n","protected":false},"author":5,"featured_media":857,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"_links":{"self":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=854"}],"version-history":[{"count":1,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/854\/revisions"}],"predecessor-version":[{"id":856,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/854\/revisions\/856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/media\/857"}],"wp:attachment":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}