{"id":845,"date":"2026-05-04T16:15:12","date_gmt":"2026-05-04T19:15:12","guid":{"rendered":"https:\/\/ibateagora.com.br\/?p=845"},"modified":"2026-05-05T09:30:30","modified_gmt":"2026-05-05T12:30:30","slug":"individuos-fogem-ao-avistar-gcm-no-cruzado","status":"publish","type":"post","link":"https:\/\/ibateagora.com.br\/index.php\/2026\/05\/04\/individuos-fogem-ao-avistar-gcm-no-cruzado\/","title":{"rendered":"Indiv\u00edduos fogem ao avistar GCM no Cruzado"},"content":{"rendered":"<p>Durante patrulhamento pela Rua Benedito Barreto, a equipe visualizou quatro indiv\u00edduos em atitude suspeita, pr\u00f3ximos a uma lixeira. Ao perceberem a presen\u00e7a da viatura, os indiv\u00edduos evadiram-se rapidamente do local, tomando rumo ignorado.<br \/>\nDiante da fundada suspeita, foi realizada averigua\u00e7\u00e3o na referida lixeira, sendo localizada uma sacola contendo subst\u00e2ncias entorpecentes, assim discriminadas:<\/p>\n<p>15 por\u00e7\u00f5es de maconha;<\/p>\n<p>31 por\u00e7\u00f5es de coca\u00edna;<\/p>\n<p>27 por\u00e7\u00f5es de haxixe;<\/p>\n<p>41 por\u00e7\u00f5es crack.<\/p>\n<p>R$10,00 em Dinheiro<\/p>\n<p>Diante dos fatos, todo o material foi recolhido e apresentado na Delegacia de Pol\u00edcia de Ibat\u00e9.<\/p>\n<p>Os itens foram devidamente lacrados no local, preservando suas caracter\u00edsticas, para fins de exibi\u00e7\u00e3o e apreens\u00e3o pela autoridade competente.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-845 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ibateagora.com.br\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-15.26.21.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/ibateagora.com.br\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-15.26.21-80x80.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Durante patrulhamento pela Rua Benedito Barreto, a equipe visualizou quatro indiv\u00edduos em atitude suspeita, pr\u00f3ximos a uma lixeira. Ao perceberem a presen\u00e7a da viatura, os indiv\u00edduos evadiram-se rapidamente do local, tomando rumo ignorado. Diante da fundada suspeita, foi realizada averigua\u00e7\u00e3o na referida lixeira, sendo localizada uma sacola contendo subst\u00e2ncias entorpecentes, assim discriminadas: 15 por\u00e7\u00f5es de<\/p>\n","protected":false},"author":5,"featured_media":846,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"_links":{"self":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=845"}],"version-history":[{"count":1,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/845\/revisions"}],"predecessor-version":[{"id":847,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/845\/revisions\/847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/media\/846"}],"wp:attachment":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}