{"id":786,"date":"2026-05-01T10:44:57","date_gmt":"2026-05-01T13:44:57","guid":{"rendered":"https:\/\/ibateagora.com.br\/?p=786"},"modified":"2026-05-04T08:15:20","modified_gmt":"2026-05-04T11:15:20","slug":"mobilidade-limpeza-urbana-e-estrutura-da-cidade-entram-na-pauta","status":"publish","type":"post","link":"https:\/\/ibateagora.com.br\/index.php\/2026\/05\/01\/mobilidade-limpeza-urbana-e-estrutura-da-cidade-entram-na-pauta\/","title":{"rendered":"Mobilidade, limpeza urbana e estrutura da cidade entram na pauta"},"content":{"rendered":"<p>A sess\u00e3o do dia 27 de Abril tamb\u00e9m foi marcada por uma s\u00e9rie de indica\u00e7\u00f5es voltadas \u00e0 melhoria da estrutura urbana. Entre elas, o vereador Joninha do Mel (PSB) prop\u00f4s a realiza\u00e7\u00e3o de estudos para implanta\u00e7\u00e3o de motofaixas nas principais avenidas da cidade. A medida sugere uma preocupa\u00e7\u00e3o com a seguran\u00e7a vi\u00e1ria e com a reorganiza\u00e7\u00e3o do tr\u00e2nsito diante do aumento de motocicletas em circula\u00e7\u00e3o.<\/p>\n<p>A vereadora Ivani do Cruzado (PSDB) apresentou indica\u00e7\u00e3o para oficiar a empresa Rumo Log\u00edstica, solicitando a limpeza do matagal na faixa de pedestres localizada no bairro Encanto do Planalto, no sentido Centro. O pedido foi aprovado por unanimidade e reflete uma cobran\u00e7a antiga de moradores sobre manuten\u00e7\u00e3o urbana e seguran\u00e7a de pedestres.<\/p>\n<p>Ivani tamb\u00e9m defendeu o envio de of\u00edcio ao governador do Estado de S\u00e3o Paulo pedindo caminh\u00e3o-pipa para a Defesa Civil e um ve\u00edculo para o departamento de transporte em apoio \u00e0 sa\u00fade. O pedido foi aprovado por unanimidade, refor\u00e7ando que o munic\u00edpio busca apoio estadual para suprir demandas operacionais.<\/p>\n<p>J\u00e1 o vereador Val Construtor (PSD) concentrou suas indica\u00e7\u00f5es em quest\u00f5es pr\u00e1ticas da mobilidade e da manuten\u00e7\u00e3o urbana. Entre os pedidos, est\u00e3o a limpeza da vegeta\u00e7\u00e3o na faixa de dom\u00ednio sob concess\u00e3o da Ecovias Noroeste Paulista, entre o km 247 e o final do bairro Popular, nas proximidades do Complexo Esportivo Parrel\u00e3o; a instala\u00e7\u00e3o de placa para vaga de embarque e desembarque em supermercados; o cal\u00e7amento de cal\u00e7ada na Rua Santa L\u00facia; a instala\u00e7\u00e3o de placa proibindo estacionamento de caminh\u00e3o na Rua Angelo Peruchi, em frente ao gin\u00e1sio de esportes; e a coloca\u00e7\u00e3o de tachas de sinaliza\u00e7\u00e3o nas rotat\u00f3rias, especialmente em pontos considerados problem\u00e1ticos. Parte dessas propostas foi aprovada por unanimidade, demonstrando converg\u00eancia entre os vereadores em temas ligados ao cotidiano da cidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A sess\u00e3o do dia 27 de Abril tamb\u00e9m foi marcada por uma s\u00e9rie de indica\u00e7\u00f5es voltadas \u00e0 melhoria da estrutura urbana. Entre elas, o vereador Joninha do Mel (PSB) prop\u00f4s a realiza\u00e7\u00e3o de estudos para implanta\u00e7\u00e3o de motofaixas nas principais avenidas da cidade. A medida sugere uma preocupa\u00e7\u00e3o com a seguran\u00e7a vi\u00e1ria e com a<\/p>\n","protected":false},"author":5,"featured_media":787,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=786"}],"version-history":[{"count":1,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/786\/revisions"}],"predecessor-version":[{"id":788,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/786\/revisions\/788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/media\/787"}],"wp:attachment":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}