{"id":649,"date":"2026-04-23T09:30:59","date_gmt":"2026-04-23T12:30:59","guid":{"rendered":"https:\/\/ibateagora.com.br\/?p=649"},"modified":"2026-04-23T09:30:59","modified_gmt":"2026-04-23T12:30:59","slug":"traficante-foge-da-gcm-pulando-telhados-em-ibate","status":"publish","type":"post","link":"https:\/\/ibateagora.com.br\/index.php\/2026\/04\/23\/traficante-foge-da-gcm-pulando-telhados-em-ibate\/","title":{"rendered":"Traficante foge da GCM pulando telhados em Ibat\u00e9"},"content":{"rendered":"<p>Em patrulhamento pela Rua Borborema, a guarni\u00e7\u00e3o visualizou um indiv\u00edduo em atitude suspeita.<br \/>\nFoi realizada a abordagem, sendo procedida busca pessoal, n\u00e3o sendo localizado nenhum objeto il\u00edcito em sua posse.<\/p>\n<p>Durante averigua\u00e7\u00e3o nas imedia\u00e7\u00f5es do local onde o indiv\u00edduo se encontrava, mais precisamente junto a uma \u00e1rvore, sob uma pedra solta, foi localizada uma sacola pl\u00e1stica transparente contendo 27 (vinte e sete) pinos de subst\u00e2ncia aparentando ser coca\u00edna.<\/p>\n<p>Ao ser indagado sobre o entorpecente localizado, o indiv\u00edduo empreendeu fuga a p\u00e9, percorrendo aproximadamente dois quarteir\u00f5es at\u00e9 a Rua Nova Europa, onde pulou o muro de uma constru\u00e7\u00e3o, transitando sobre diversos telhados e tomando rumo ignorado.<\/p>\n<p>Apesar do acompanhamento, n\u00e3o foi poss\u00edvel a deten\u00e7\u00e3o do indiv\u00edduo.<\/p>\n<p>O material apreendido foi encaminhado ao Plant\u00e3o Policial de S\u00e3o Carlos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em patrulhamento pela Rua Borborema, a guarni\u00e7\u00e3o visualizou um indiv\u00edduo em atitude suspeita. Foi realizada a abordagem, sendo procedida busca pessoal, n\u00e3o sendo localizado nenhum objeto il\u00edcito em sua posse. Durante averigua\u00e7\u00e3o nas imedia\u00e7\u00f5es do local onde o indiv\u00edduo se encontrava, mais precisamente junto a uma \u00e1rvore, sob uma pedra solta, foi localizada uma sacola<\/p>\n","protected":false},"author":5,"featured_media":650,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31,36,39,40],"class_list":["post-649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-drogas","tag-gcm","tag-policia","tag-traficante"],"_links":{"self":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=649"}],"version-history":[{"count":1,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/649\/revisions"}],"predecessor-version":[{"id":651,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/649\/revisions\/651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/media\/650"}],"wp:attachment":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}