{"id":1000,"date":"2026-05-08T08:17:43","date_gmt":"2026-05-08T11:17:43","guid":{"rendered":"https:\/\/ibateagora.com.br\/?p=1000"},"modified":"2026-05-12T14:09:10","modified_gmt":"2026-05-12T17:09:10","slug":"operacao-saturacao-resulta-em-apreensao-de-drogas-no-cruzado","status":"publish","type":"post","link":"https:\/\/ibateagora.com.br\/index.php\/2026\/05\/08\/operacao-saturacao-resulta-em-apreensao-de-drogas-no-cruzado\/","title":{"rendered":"Opera\u00e7\u00e3o satura\u00e7\u00e3o resulta em apreens\u00e3o de drogas no Cruzado"},"content":{"rendered":"<p>Durante uma opera\u00e7\u00e3o conjunta de satura\u00e7\u00e3o realizada pela Pol\u00edcia Militar e Guarda Civil Municipal na regi\u00e3o do Cruzado, as equipes ingressaram na Rua Benedito Barreto, observaram um indiv\u00edduo em atitude suspeita na pra\u00e7a pr\u00f3xima ao PSF.<\/p>\n<p>Ao notar a aproxima\u00e7\u00e3o das equipes, o suspeito evadiu-se e ocultou uma m\u00e1quina de cart\u00e3o no pneu de um \u00f4nibus estacionado na Rua Nova Europa. Na abordagem, n\u00e3o foram encontrados objetos il\u00edcitos em sua posse.<\/p>\n<p>Entretanto, durante varredura nas imedia\u00e7\u00f5es, foi localizada uma sacola preta no interior do PSF contendo entorpecentes, dinheiro em esp\u00e9cie e itens relacionados \u00e0 pr\u00e1tica de tr\u00e1fico de drogas.<\/p>\n<p>O suspeito negou envolvimento com o delito. Posteriormente, compareceu ao local um indiv\u00edduo portando uma crian\u00e7a, solicitando a devolu\u00e7\u00e3o de um cart\u00e3o banc\u00e1rio que estava com o abordado. Questionado acerca da presen\u00e7a do cart\u00e3o, informou ter ido ao local para adquirir um cigarro de maconha, confirmando ind\u00edcios relativos ao tr\u00e1fico de entorpecentes.<\/p>\n<p>Diante dos fatos, foi dada voz de pris\u00e3o ao suspeito, que ap\u00f3s exame de corpo de delito no hospital, foi apresentado na Delegacia de Pol\u00edcia de S\u00e3o Carlos, sendo ouvido e posteriormente liberado.<\/p>\n<p>Materiais apreendidos:<\/p>\n<p>74 tubos com coca\u00edna;<\/p>\n<p>30 por\u00e7\u00f5es de maconha;<\/p>\n<p>28 por\u00e7\u00f5es de crack;<\/p>\n<p>03 por\u00e7\u00f5es de \u201cdry\u201d;<\/p>\n<p>01 m\u00e1quina de cart\u00e3o, com saldo di\u00e1rio aproximado de R$ 2.362,00;<\/p>\n<p>R$ 220,00 em notas;<\/p>\n<p>R$ 5,00 em moedas;<\/p>\n<p>01 aparelho celular iPhone, cor prata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante uma opera\u00e7\u00e3o conjunta de satura\u00e7\u00e3o realizada pela Pol\u00edcia Militar e Guarda Civil Municipal na regi\u00e3o do Cruzado, as equipes ingressaram na Rua Benedito Barreto, observaram um indiv\u00edduo em atitude suspeita na pra\u00e7a pr\u00f3xima ao PSF. Ao notar a aproxima\u00e7\u00e3o das equipes, o suspeito evadiu-se e ocultou uma m\u00e1quina de cart\u00e3o no pneu de um<\/p>\n","protected":false},"author":5,"featured_media":1001,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"_links":{"self":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1000"}],"version-history":[{"count":1,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1000\/revisions"}],"predecessor-version":[{"id":1002,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1000\/revisions\/1002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/media\/1001"}],"wp:attachment":[{"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibateagora.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}